{"id":5407,"date":"2021-01-20T21:54:40","date_gmt":"2021-01-20T21:54:40","guid":{"rendered":"https:\/\/sg-ea.caseproof.com\/?post_type=docs&#038;p=111"},"modified":"2022-08-04T21:19:21","modified_gmt":"2022-08-04T21:19:21","password":"","slug":"commissions-not-tracking","status":"publish","type":"docs","link":"https:\/\/easyaffiliate.com\/es\/docs\/commissions-not-tracking\/","title":{"rendered":"No se siguen las comisiones"},"content":{"rendered":"<p>Si sospecha que el seguimiento de sus comisiones no es fiable, compruebe las siguientes causas comunes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"caching\"><strong>Almacenamiento en cach\u00e9<\/strong><\/h2>\n\n\n\n<p>Hemos descubierto que las configuraciones de cach\u00e9 agresivas como Varnish o Memcached a menudo impiden que se establezcan cookies de seguimiento cuando un usuario hace clic en un enlace de afiliado. Sin la cookie, no se puede rastrear nada. <\/p>\n\n\n\n<p>La forma m\u00e1s f\u00e1cil de comprobarlo es copiar uno de los enlaces de tu afiliado y pegarlo en una herramienta como \u00e9sta: <a rel=\"noreferrer noopener\" href=\"https:\/\/websniffer.cc\/\" target=\"_blank\">https:\/\/websniffer.cc\/<\/a>. En primer lugar, pegue uno de sus enlaces de afiliado y haga clic en Enviar. A continuaci\u00f3n, despl\u00e1cese hasta la tabla HTTP Response Header y busque Set-Cookie: row. Compruebe si <strong>esaf_click<\/strong> est\u00e1 en la lista. Si no es as\u00ed, lo m\u00e1s probable es que haya un problema de cach\u00e9 o de configuraci\u00f3n del alojamiento que impida que se instalen las cookies. Tendr\u00e1s que trabajar con tu proveedor de alojamiento web para corregir este problema.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"user-disabled-deleted-cookies\"><strong>Cookies desactivadas\/borradas por el usuario<\/strong><\/h2>\n\n\n\n<p>Si el invitado (usuario que ha hecho clic en el enlace del afiliado) tiene desactivadas las cookies en su navegador, o si borra con frecuencia su historial de cookies, no se podr\u00e1 realizar el seguimiento de una comisi\u00f3n, ya que la cookie es el enlace que conecta al invitado con el afiliado. Tenga en cuenta que es bastante raro que los usuarios tengan deshabilitadas las cookies.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"user-bought-on-another-device-browser\"><strong>Usuario comprado en otro dispositivo\/navegador<\/strong><\/h2>\n\n\n\n<p>Si el invitado hace clic en un enlace de afiliado y m\u00e1s tarde visita su sitio directamente en un dispositivo o navegador diferente, la cookie no estar\u00e1 presente y no se podr\u00e1 realizar el seguimiento de la comisi\u00f3n. Tenga en cuenta que esto es bastante raro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"user-bought-on-another-device-browser\"><strong>La venta se produjo en un sitio diferente<\/strong><\/h2>\n\n\n\n<p>Para obtener los mejores resultados, Easy Affiliate debe instalarse en el mismo sitio en el que se realiza la venta. Easy Affiliate cuenta con integraciones para WooCommerce, MemberPress, Easy Digital Downloads y botones de PayPal. <\/p>\n\n\n\n<p>Es posible integrarlo con otros sistemas, pero puede requerir plugins de terceros o un desarrollo personalizado. Si necesita m\u00e1s informaci\u00f3n, por favor <a href=\"https:\/\/easyaffiliate.com\/es\/support\/\">contactar con el servicio de asistencia<\/a>. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"fraud-prevention-enabled\"><strong>Prevenci\u00f3n del fraude<\/strong><\/h2>\n\n\n\n<p>Si tiene el <a href=\"https:\/\/easyaffiliate.com\/es\/docs\/fraud-prevention-add-on\/\" target=\"_blank\" rel=\"noreferrer noopener\">Complemento de prevenci\u00f3n del fraude<\/a> instalado, y est\u00e1 configurado para rechazar cualquier clic en el que el remitente no proviene de uno de los sitios web que figuran en la aplicaci\u00f3n del afiliado - <a href=\"https:\/\/share.cspf.co\/L1urLgl6\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/share.cspf.co\/L1urLgl6<\/a> no se contabilizar\u00eda ninguna venta realizada desde un enlace publicado en un sitio web diferente.<\/p>\n\n\n\n<p>Si lo hubiera puesto en <em>Permitir<\/em> o desactivar el complemento de prevenci\u00f3n de fraudes, se establecer\u00eda la cookie al visitar la URL de afiliado en cualquier sitio web.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"transaction-too-small\"><strong>Transacci\u00f3n demasiado peque\u00f1a<\/strong><\/h2>\n\n\n\n<p>Si realiza una transacci\u00f3n inferior a $1 (o 1\u20ac o equivalente en otra divisa), no se realizar\u00e1 el seguimiento de la comisi\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"woocommerce\"><strong>WooCommerce<\/strong><\/h2>\n\n\n\n<p>Si est\u00e1s rastreando comisiones de ventas de WooCommerce, aseg\u00farate de que tus Pedidos de WooCommerce est\u00e1n siendo marcados como \"Completos\".<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"memberpress\"><strong>MiembroPrensa<\/strong><\/h2>\n\n\n\n<p>Si est\u00e1 realizando un seguimiento de las comisiones de las ventas de MemberPress, aseg\u00farese de que las transacciones de MemberPress se muestren como \"Completadas\" autom\u00e1ticamente despu\u00e9s de que el invitado compre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"paypal\"><strong>PayPal<\/strong><\/h2>\n\n\n\n<p>Si va a realizar la integraci\u00f3n con botones de PayPal, aseg\u00farese de seguir exactamente los pasos de los botones. Omitir un solo paso puede impedir el correcto seguimiento de las comisiones.<\/p>\n\n\n\n<p>Si ninguna de las opciones anteriores es aplicable, por favor <a href=\"https:\/\/easyaffiliate.com\/es\/support\/\">contacte con nuestro equipo de asistencia<\/a> para obtener m\u00e1s ayuda.<\/p>","protected":false},"excerpt":{"rendered":"<p>If you suspect that your commissions may not be tracking reliably, then please go through and check the following common causes. Caching We&#8217;ve found that aggressive caching setups like Varnish or Memcached often prevent tracking cookies from being set when a user clicks on an affiliate link. Without the cookie, nothing can be tracked. The [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"doc_category":[310],"doc_tag":[],"class_list":{"0":"post-5407","1":"docs","2":"type-docs","3":"status-publish","5":"doc_category-troubleshooting","6":"entry"},"acf":[],"aioseo_notices":[],"year_month":"2026-05","word_count":487,"total_views":"0","reactions":{"happy":"381","normal":"14","sad":"2"},"author_info":{"name":"Blair Williams","author_nicename":"supercleanse","author_url":"https:\/\/easyaffiliate.com\/es\/blog\/author\/supercleanse\/"},"doc_category_info":[{"term_name":"Troubleshooting","term_url":"https:\/\/easyaffiliate.com\/es\/docs-category\/troubleshooting\/"}],"doc_tag_info":[],"_links":{"self":[{"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/docs\/5407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/comments?post=5407"}],"version-history":[{"count":0,"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/docs\/5407\/revisions"}],"wp:attachment":[{"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/media?parent=5407"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/doc_category?post=5407"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/doc_tag?post=5407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}