{"id":2361,"date":"2017-06-19T18:54:13","date_gmt":"2017-06-19T18:54:13","guid":{"rendered":"http:\/\/easyaffiliate.wpengine.com\/?p=2361"},"modified":"2024-06-13T15:38:14","modified_gmt":"2024-06-13T15:38:14","slug":"find-quality-affiliates","status":"publish","type":"post","link":"https:\/\/easyaffiliate.com\/es\/blog\/find-quality-affiliates\/","title":{"rendered":"3 Consejos estelares para reclutar afiliados de calidad para su programa"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04f4c757c31\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04f4c757c31\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/easyaffiliate.com\/es\/blog\/find-quality-affiliates\/#Why_Quality_Affiliates_Are_Important\" >Por qu\u00e9 son importantes los afiliados de calidad<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/easyaffiliate.com\/es\/blog\/find-quality-affiliates\/#3_Stellar_Tips_for_Recruiting_Quality_Affiliates_to_Your_Program\" >3 Consejos estelares para reclutar afiliados de calidad para su programa<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/easyaffiliate.com\/es\/blog\/find-quality-affiliates\/#1_Actively_Network_on_Social_Media\" >1. Con\u00e9ctese activamente a las redes sociales<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/easyaffiliate.com\/es\/blog\/find-quality-affiliates\/#2_Reward_Affiliates_for_Their_Recruitment_Efforts\" >2. Recompensar a los afiliados por sus esfuerzos de captaci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/easyaffiliate.com\/es\/blog\/find-quality-affiliates\/#3_Partner_With_Like-Minded_Businesses\" >3. Asociarse con empresas afines<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/easyaffiliate.com\/es\/blog\/find-quality-affiliates\/#Conclusion\" >Conclusi\u00f3n<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>La calidad de los afiliados de su programa contribuir\u00e1 significativamente al \u00e9xito de su negocio. Por este motivo, encontrar a los mejores afiliados posibles es un paso del proceso de captaci\u00f3n que no puede permitirse pasar por alto. Sin embargo, aunque tenga <a href=\"https:\/\/easyaffiliate.com\/es\/2017\/04\/create-affiliate-program\/\" target=\"_blank\" rel=\"noopener noreferrer\">un s\u00f3lido programa de afiliaci\u00f3n<\/a> en su sitio, es posible que a\u00fan le cueste encontrar el <a href=\"https:\/\/www.amnavigator.com\/blog\/2015\/07\/22\/characteristics-of-valuable-affiliate\/\" target=\"_blank\" rel=\"noopener noreferrer\">candidatos adecuados<\/a>.<\/p>\n\n\n\n<p>Afortunadamente, es posible reclutar afiliados valiosos para su programa sin tener que rebuscar entre docenas de solicitudes. Siguiendo algunas estrategias b\u00e1sicas, puede completar este proceso de forma r\u00e1pida y eficaz.<\/p>\n\n\n\n<p>En este art\u00edculo, primero analizaremos por qu\u00e9 los afiliados de calidad son tan importantes. Luego esbozaremos tres consejos estelares que le ayudar\u00e1n a encontrar y reclutar afiliados de calidad para su programa. Empecemos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Why_Quality_Affiliates_Are_Important\"><\/span>Por qu\u00e9 son importantes los afiliados de calidad<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Los afiliados son el alma de su programa, por lo que es esencial que haga la mejor selecci\u00f3n posible. Aunque la calidad puede ser subjetiva, hay dos elementos concretos que contribuyen a este criterio. Querr\u00e1 buscar afiliados con experiencia y conocimientos del sector, as\u00ed como aquellos que <a href=\"https:\/\/easyaffiliate.com\/es\/2017\/05\/transparency-in-affiliate-marketing\/\" target=\"_blank\" rel=\"noopener noreferrer\">en quien confiar<\/a> seguir las pol\u00edticas del programa y representar a su empresa.<\/p>\n\n\n\n<p>Una de las formas m\u00e1s obvias en que estos afiliados de alta calidad pueden beneficiar a su negocio es a trav\u00e9s del aumento de las ventas. Adem\u00e1s, cuando trabajas con afiliados incre\u00edbles, ellos tambi\u00e9n pueden animar a otros a unirse a tu programa. Por lo tanto, encontrar a los afiliados adecuados para tu negocio deber\u00eda ser una prioridad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_Stellar_Tips_for_Recruiting_Quality_Affiliates_to_Your_Program\"><\/span>3 Consejos estelares para reclutar afiliados de calidad para su programa<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Aunque encontrar afiliados de calidad puede parecer una tarea desalentadora al principio, hay una serie de estrategias sencillas que pueden reforzar sus esfuerzos. Veamos algunas de las mejores.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_Actively_Network_on_Social_Media\"><\/span>1. Con\u00e9ctese activamente a las redes sociales<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Como vendedor, es posible que ya utilice <a href=\"https:\/\/easyaffiliate.com\/es\/2017\/03\/link-shortening-your-secret-weapon-in-social-media-marketing\/\" target=\"_blank\" rel=\"noopener noreferrer\">redes sociales<\/a> para llegar a nuevos clientes potenciales. Sin embargo, las redes sociales tambi\u00e9n pueden ayudarle a mejorar sus esfuerzos de captaci\u00f3n de afiliados.<\/p>\n\n\n\n<p>Utilizar las redes sociales de esta forma tiene dos ventajas principales. En primer lugar, una presencia activa le convierte en una empresa cre\u00edble, lo que mejora su programa de afiliaci\u00f3n. En segundo lugar, le ayuda a ampliar su alcance y abrir sus productos de afiliaci\u00f3n a nuevos p\u00fablicos. Esto allana el camino para la captaci\u00f3n de afiliados a los que de otro modo no habr\u00edas podido llegar.<\/p>\n\n\n\n<p>Para aplicar esta estrategia, tendr\u00e1 que&nbsp;<a href=\"https:\/\/digitalmarketinginstitute.com\/blog\/2016-10-26-how-to-choose-the-best-social-media-channels-for-your-business\" target=\"_blank\" rel=\"noopener noreferrer\">elegir la plataforma adecuada<\/a> para atraer a afiliados del sector. Puede hacerlo analizando&nbsp;<a href=\"http:\/\/www.pewinternet.org\/2016\/11\/11\/social-media-update-2016\/\" target=\"_blank\" rel=\"noopener noreferrer\">demograf\u00eda de la audiencia<\/a>&nbsp;(en este caso, tu \"p\u00fablico\" son los afiliados). Cuando hayas elegido la plataforma adecuada, es importante que <a href=\"https:\/\/blog.kissmetrics.com\/help-customers-find-you\/\" target=\"_blank\" rel=\"noopener noreferrer\">incorporar palabras clave espec\u00edficas<\/a>&nbsp;en sus contenidos y siga las normas espec\u00edficas de cada plataforma, como el uso de <a href=\"https:\/\/www.facebook.com\/about\/mentions\/\" target=\"_blank\" rel=\"noopener noreferrer\">Menciones<\/a> en Facebook o hashtags en Twitter:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"878\" height=\"260\" src=\"https:\/\/easyaffiliate.com\/wp-content\/uploads\/2017\/06\/hashtag-example.jpg\" alt=\"Un ejemplo de uso de palabras clave en forma de hashtag en Twitter\" class=\"wp-image-2365\" srcset=\"https:\/\/easyaffiliate.com\/wp-content\/uploads\/2017\/06\/hashtag-example.jpg 878w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2017\/06\/hashtag-example-300x89.jpg 300w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2017\/06\/hashtag-example-768x227.jpg 768w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2017\/06\/hashtag-example-480x142.jpg 480w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2017\/06\/hashtag-example-156x46.jpg 156w\" sizes=\"(max-width: 878px) 100vw, 878px\" \/><\/figure>\n\n\n\n<p>En general, <a href=\"https:\/\/www.inc.com\/eric-v-holtzclaw\/consistency-power-success-rules.html\" target=\"_blank\" rel=\"noopener noreferrer\">la coherencia es la clave<\/a>&nbsp;en las redes sociales. Esto significa que debes mantenerte activo en tus cuentas, participando con frecuencia en debates y compartiendo contenidos valiosos. Te recomendamos que empieces con una o dos plataformas para centrarte en ellas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2_Reward_Affiliates_for_Their_Recruitment_Efforts\"><\/span>2. Recompensar a los afiliados por sus esfuerzos de captaci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Adem\u00e1s de promocionar sus productos, sus afiliados tambi\u00e9n pueden ayudar a defender su programa. Esto puede aliviar su carga y aumentar el n\u00famero de afiliados de calidad.<\/p>\n\n\n\n<p>Ofrecer a sus afiliados recompensas por sus esfuerzos de captaci\u00f3n les proporciona motivaci\u00f3n. En particular, las recompensas recurrentes (como permitir que sus afiliados ganen un porcentaje de las ventas de sus reclutas) les motivan a seleccionar nuevos afiliados que creen que tendr\u00e1n un buen rendimiento. Usted sale ganando.<\/p>\n\n\n\n<p>Su primer paso en esta estrategia ser\u00e1 seleccionar un tipo de recompensa. Esto significa decidir entre una recompensa \u00fanica o recurrente y <a href=\"http:\/\/www.coastdigital.co.uk\/2013\/02\/05\/how-to-incentivise-affiliates-encourage-to-promote-you\/\" target=\"_blank\" rel=\"noopener noreferrer\">determinar su forma exacta<\/a>. Entonces tendr\u00e1s que poner en pr\u00e1ctica esa recompensa. Cuando utilice <a href=\"https:\/\/easyaffiliate.com\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Afiliaci\u00f3n f\u00e1cil<\/a>es una tarea sencilla porque nuestro plugin le permite <a href=\"https:\/\/easyaffiliate.com\/es\/docs\/commission-levels-add-on\/\" target=\"_blank\" rel=\"noreferrer noopener\">establecer niveles de afiliaci\u00f3n<\/a>:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"879\" height=\"561\" src=\"https:\/\/easyaffiliate.com\/wp-content\/uploads\/2021\/04\/Settings-\u2039-Mem.png\" alt=\"niveles de comisi\u00f3n \" class=\"wp-image-5612\" srcset=\"https:\/\/easyaffiliate.com\/wp-content\/uploads\/2021\/04\/Settings-\u2039-Mem.png 879w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2021\/04\/Settings-\u2039-Mem-300x191.png 300w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2021\/04\/Settings-\u2039-Mem-768x490.png 768w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2021\/04\/Settings-\u2039-Mem-222x142.png 222w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2021\/04\/Settings-\u2039-Mem-423x270.png 423w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2021\/04\/Settings-\u2039-Mem-156x100.png 156w\" sizes=\"(max-width: 879px) 100vw, 879px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-color\" style=\"color:#222222\">Todo lo que tiene que hacer es dirigirse a&nbsp;<em>Afiliaci\u00f3n f\u00e1cil&nbsp;<\/em>&gt;&nbsp;<em>Configuraci\u00f3n &gt; Comisiones. <\/em> A continuaci\u00f3n, puede establecer tasas de comisi\u00f3n por nivel de afiliado. Para <a href=\"https:\/\/easyaffiliate.com\/es\/docs\/settings-commissions-tab\/\" target=\"_blank\" rel=\"noreferrer noopener\">suscripciones<\/a>puede elegir en qu\u00e9 transacciones pagar comisiones. Compruebe la&nbsp;<em>Pagar comisi\u00f3n s\u00f3lo en la primera venta <\/em>si desea que los afiliados reciban un pago \u00fanico. O haga clic en el bot\u00f3n <em>Pago de comisiones por todas las ventas<\/em> si desea pagar a los afiliados cada vez que se renueve una suscripci\u00f3n.<\/p>\n\n\n\n<p>Cuando haya terminado, haga clic en el bot\u00f3n azul <em>Opciones de actualizaci\u00f3n<\/em> en la parte inferior de la p\u00e1gina.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_Partner_With_Like-Minded_Businesses\"><\/span>3. Asociarse con empresas afines<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Gracias a <a href=\"https:\/\/techgeek365.com\/affiliate-marketing-growing-popularity\/\" target=\"_blank\" rel=\"noopener noreferrer\">la creciente popularidad del marketing de afiliaci\u00f3n<\/a>En la actualidad, tiene a su disposici\u00f3n una serie de opciones de crecimiento empresarial. Por ejemplo, puede asociarse con empresas afines para ampliar su red de afiliados. Esto significa encontrar otras empresas del sector con afiliados y trabajar con ellas para ampliar ambos programas.<\/p>\n\n\n\n<p>Lo mejor de este tipo de asociaci\u00f3n es que te da acceso a una lista de afiliados ya establecida. Aunque esto no significa autom\u00e1ticamente que vaya a ganar <i>todos <\/i>de los afiliados de su socio, su presencia en las redes sociales y los incentivos para afiliados (como se indica en los dos consejos anteriores) pueden ayudar a atraer a muchos de esos afiliados a su programa.<\/p>\n\n\n\n<p>Por supuesto, primero tendr\u00e1 que localizar empresas complementarias que no sean competidoras en su sector. Por ejemplo, si vende equipos de fitness, podr\u00eda asociarse con una empresa de alimentos saludables que tenga un programa de afiliaci\u00f3n activo. Puede que necesite <a href=\"http:\/\/articles.bplans.com\/how-to-find-a-business-partner\/\" target=\"_blank\" rel=\"noopener noreferrer\">un poco de trabajo<\/a> para encontrar la pareja adecuada, pero aqu\u00ed tienes dos consejos para empezar:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Utiliza tus contactos.\u00a0<\/strong>Si tiene<strong>\u00a0<\/strong>una presencia activa en las redes sociales, es probable que sepa\u00a0<em>alguien<\/em> (aunque sea indirectamente) que ser\u00eda un gran socio.<\/li>\n\n\n\n<li><strong>Asista a eventos del sector.<\/strong>\u00a0Es una forma perfecta de ampliar su red de contactos al mundo real y conocer personalmente a posibles socios comerciales.<\/li>\n<\/ol>\n\n\n\n<p>Tambi\u00e9n es una buena idea ofrecer <a href=\"https:\/\/easyaffiliate.com\/es\/2017\/05\/determine-commission-rates-affiliate-marketing\/\" target=\"_blank\" rel=\"noopener noreferrer\">una tasa de comisi\u00f3n especial para afiliados<\/a> a los afiliados de su nuevo socio. Esto animar\u00e1 a m\u00e1s reci\u00e9n llegados a dar el paso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Conclusi\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Un programa de afiliaci\u00f3n fuerte y exitoso se apoya en una base de afiliados de calidad. Por lo tanto, es esencial perfeccionar sus esfuerzos de captaci\u00f3n y centrarse en encontrar a los afiliados que mejor se adapten a su programa.<\/p>\n\n\n\n<p>En este post, hemos esbozado tres consejos que puede utilizar para encontrar y reclutar afiliados de calidad. Para recapitular r\u00e1pidamente, son:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Con\u00e9ctate activamente a las redes sociales.<\/li>\n\n\n\n<li>Recompense a los afiliados por sus esfuerzos de captaci\u00f3n.<\/li>\n\n\n\n<li>As\u00f3ciese con empresas afines.<\/li>\n<\/ol>\n\n\n\n<p>\u00bfTiene alguna pregunta acerca de c\u00f3mo reclutar afiliados de calidad a su programa, o c\u00f3mo <a href=\"https:\/\/easyaffiliate.com\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Afiliaci\u00f3n f\u00e1cil<\/a> \u00bfpuede ayudarle? H\u00e1ganoslo saber en la secci\u00f3n de comentarios.<\/p>\n\n\n\n<p>Si te ha gustado este post, no dejes de seguirnos en <a href=\"https:\/\/twitter.com\/easyaffapp\"><strong>Twitter<\/strong><\/a>, <a href=\"https:\/\/www.facebook.com\/easyaffiliateplugin\"><strong>Facebook<\/strong><\/a>y <a href=\"https:\/\/www.linkedin.com\/showcase\/easy-affiliate-plugin\/?viewAsMember=true\"><strong>LinkedIn<\/strong><\/a>\u00a1! Y no olvides suscribirte en el <a href=\"https:\/\/easyaffiliate.com\/es\/go\/box\/\" title=\"Enlace de afiliaci\u00f3n\" class=\"pretty-link-keyword\"rel=\"nofollow \" target=\"_blank\">caja<\/a> abajo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Descubra c\u00f3mo atraer a los mejores afiliados a su programa con nuestros 3 consejos esenciales. Mejora tu estrategia de captaci\u00f3n e impulsa los resultados.<\/p>","protected":false},"author":1592,"featured_media":5574,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_strive_checklists":"\"\"","_strive_active_checklist":"","_strive_post_notes":"","footnotes":""},"categories":[312],"tags":[327],"class_list":{"0":"post-2361","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-advice","8":"tag-affiliate-recruiting","9":"entry"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/posts\/2361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/users\/1592"}],"replies":[{"embeddable":true,"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/comments?post=2361"}],"version-history":[{"count":0,"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/posts\/2361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/media\/5574"}],"wp:attachment":[{"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/media?parent=2361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/categories?post=2361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/easyaffiliate.com\/es\/wp-json\/wp\/v2\/tags?post=2361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}