{"id":3447,"date":"2018-08-20T21:22:49","date_gmt":"2018-08-20T21:22:49","guid":{"rendered":"http:\/\/easyaffiliate.wpengine.com\/?p=3447"},"modified":"2024-06-10T11:29:21","modified_gmt":"2024-06-10T11:29:21","slug":"ways-to-create-powerful-call-to-action","status":"publish","type":"post","link":"https:\/\/easyaffiliate.com\/pt\/blog\/ways-to-create-powerful-call-to-action\/","title":{"rendered":"3 maneiras de criar uma chamada \u00e0 a\u00e7\u00e3o poderosa"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04ef116a0ed\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Alternar<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04ef116a0ed\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/easyaffiliate.com\/pt\/blog\/ways-to-create-powerful-call-to-action\/#An_Introduction_to_the_Call_To_Action_CTA\" >Uma introdu\u00e7\u00e3o \u00e0 chamada para a\u00e7\u00e3o (CTA)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/easyaffiliate.com\/pt\/blog\/ways-to-create-powerful-call-to-action\/#3_Ways_to_Create_a_Powerful_CTA_for_Your_Website\" >3 maneiras de criar uma CTA poderosa para seu site<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/easyaffiliate.com\/pt\/blog\/ways-to-create-powerful-call-to-action\/#1_Make_the_Message_Engaging_and_Persuasive\" >1. Torne a mensagem envolvente e persuasiva<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/easyaffiliate.com\/pt\/blog\/ways-to-create-powerful-call-to-action\/#2_Choose_the_Right_Colors\" >2. Escolha as cores certas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/easyaffiliate.com\/pt\/blog\/ways-to-create-powerful-call-to-action\/#3_Display_Your_CTA_in_a_Prominent_Location\" >3. Exiba sua CTA em um local de destaque<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/easyaffiliate.com\/pt\/blog\/ways-to-create-powerful-call-to-action\/#Conclusion\" >Conclus\u00e3o<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>Todo site de afiliados tem um prop\u00f3sito expresso, um \u00fanico objetivo para o qual est\u00e1 orientando os visitantes: o final do funil de vendas. Antes que os visitantes possam atingir essa meta, eles precisar\u00e3o concluir uma a\u00e7\u00e3o espec\u00edfica. O segredo \u00e9 fazer com que eles deem o \u00faltimo passo.<\/p>\n\n\n\n<p>\u00c9 a\u00ed que a sua chamada para a\u00e7\u00e3o (CTA) entra em a\u00e7\u00e3o. Uma CTA \u00e9 uma mensagem que voc\u00ea apresenta ao seu p\u00fablico e que permite que ele saiba exatamente o que voc\u00ea gostaria que ele fizesse. Isso pode ser algo como concluir uma compra ou se inscrever em uma associa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Neste artigo, falaremos mais sobre as CTAs, inclusive como criar uma que possa aumentar suas convers\u00f5es. Tamb\u00e9m abordaremos algumas dicas para tornar sua CTA atraente <em>e<\/em> eficaz. Vamos l\u00e1!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"An_Introduction_to_the_Call_To_Action_CTA\"><\/span>Uma introdu\u00e7\u00e3o \u00e0 chamada para a\u00e7\u00e3o (CTA)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<div class=\"wp-block-image wp-image-3452\"><figure class=\"aligncenter\"><img decoding=\"async\" width=\"1557\" height=\"627\" src=\"https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/campaign-monitor-cta-1.jpg\" alt=\"Chamada \u00e0 a\u00e7\u00e3o do Campaign Monitor\" class=\"wp-image-3452\" srcset=\"https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/campaign-monitor-cta-1.jpg 1557w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/campaign-monitor-cta-1-300x121.jpg 300w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/campaign-monitor-cta-1-1024x412.jpg 1024w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/campaign-monitor-cta-1-768x309.jpg 768w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/campaign-monitor-cta-1-1536x619.jpg 1536w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/campaign-monitor-cta-1-353x142.jpg 353w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/campaign-monitor-cta-1-670x270.jpg 670w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/campaign-monitor-cta-1-1216x490.jpg 1216w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/campaign-monitor-cta-1-156x63.jpg 156w\" sizes=\"(max-width: 1557px) 100vw, 1557px\" \/><figcaption>Bot\u00f5es ou textos estrategicamente posicionados e projetados podem obrigar os visitantes a realizar uma a\u00e7\u00e3o espec\u00edfica.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Em termos mais simples, uma CTA \u00e9 um dispositivo de marketing usado para solicitar uma resposta imediata de seu p\u00fablico. Nos sites de afiliados, as CTAs s\u00e3o geralmente usadas para incentivar convers\u00f5es (ou seja, vendas).<\/p>\n\n\n\n<p>Dessa forma, eles podem aparecer em postagens de blog, <a href=\"https:\/\/easyaffiliate.com\/pt\/2018\/01\/create-affiliate-ads-and-links\/\" target=\"_blank\" rel=\"noopener noreferrer\">como em um banner<\/a> no meio da p\u00e1gina). Eles tamb\u00e9m podem aparecer em p\u00e1ginas de produtos, por exemplo, como um <a href=\"https:\/\/devrix.com\/tutorial\/infographic-create-call-to-action-buttons\/\" target=\"_blank\" rel=\"noopener noreferrer\">bot\u00e3o estrategicamente posicionado e projetado<\/a> com um prompt de texto.<\/p>\n\n\n\n<p>Todo neg\u00f3cio on-line usa uma CTA de uma forma ou de outra. Afinal de contas, trata-se simplesmente de uma mensagem destinada a incentivar os visitantes a realizar uma a\u00e7\u00e3o espec\u00edfica. Conforme mencionado, essa a\u00e7\u00e3o pode ser a compra de um produto, a assinatura de um boletim informativo ou a inscri\u00e7\u00e3o em uma conta ou associa\u00e7\u00e3o.<\/p>\n\n\n\n<p>No entanto, para serem eficazes, suas CTAs devem ser <a href=\"https:\/\/knowledge.hubspot.com\/cta-user-guide-v2\/call-to-action-best-practices\" target=\"_blank\" rel=\"noopener noreferrer\">claro e convincente<\/a>. Voc\u00ea n\u00e3o quer que seus visitantes tenham que <em>adivinhar<\/em> no que voc\u00ea gostaria que eles fizessem. Em vez disso, voc\u00ea precisa fornecer instru\u00e7\u00f5es expl\u00edcitas para as pr\u00f3ximas etapas e incentiv\u00e1-las a seguir em frente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_Ways_to_Create_a_Powerful_CTA_for_Your_Website\"><\/span>3 maneiras de criar uma CTA poderosa para seu site<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Agora que j\u00e1 abordamos os conceitos b\u00e1sicos, vamos dar uma olhada mais de perto em como voc\u00ea pode tornar suas CTAs mais eficientes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_Make_the_Message_Engaging_and_Persuasive\"><\/span>1. Torne a mensagem envolvente e persuasiva<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"wp-block-image wp-image-3448\"><figure class=\"aligncenter\"><img decoding=\"async\" width=\"867\" height=\"556\" src=\"https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/netflix-cta-1.jpg\" alt=\"Chamada \u00e0 a\u00e7\u00e3o convincente da Netflix\" class=\"wp-image-3448\" srcset=\"https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/netflix-cta-1.jpg 867w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/netflix-cta-1-300x192.jpg 300w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/netflix-cta-1-768x493.jpg 768w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/netflix-cta-1-221x142.jpg 221w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/netflix-cta-1-421x270.jpg 421w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/netflix-cta-1-156x100.jpg 156w\" sizes=\"(max-width: 867px) 100vw, 867px\" \/><figcaption>A Netflix usa uma CTA atraente e direta ao ponto para atrair novos assinantes.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Se o seu objetivo for uma CTA poderosa, uma mensagem envolvente e persuasiva \u00e9 imprescind\u00edvel. Criar essa mensagem significa <a href=\"https:\/\/www.marketingsherpa.com\/content_by_legacy_id?legacy_id=30124\" target=\"_blank\" rel=\"noopener noreferrer\">usar as palavras certas<\/a>. \u00c9 claro que a frase que voc\u00ea deve usar varia de acordo com seu p\u00fablico e objetivo final.<\/p>\n\n\n\n<p>Para come\u00e7ar, recomendamos que voc\u00ea:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Deixe claro o benef\u00edcio de seus produtos ou servi\u00e7os.<\/strong> Por exemplo, voc\u00ea pode oferecer <a href=\"https:\/\/www.priceintelligently.com\/blog\/bid\/188339\/Screw-Freemium-Use-a-Free-Trial\" target=\"_blank\" rel=\"noopener noreferrer\">um teste gratuito<\/a> (para que os visitantes possam testar um produto por si mesmos) ou destacar alguns depoimentos positivos de clientes.<\/li><li><strong>Uso <\/strong><a href=\"https:\/\/positivepsychologyprogram.com\/positive-emotions-list-examples-definition-psychology\/#words\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>palavras poderosas e emo\u00e7\u00f5es positivas<\/strong><\/a>. Essas op\u00e7\u00f5es evocar\u00e3o boas sensa\u00e7\u00f5es em seus visitantes, o que pode obrig\u00e1-los a clicar para ir para a pr\u00f3xima etapa.<\/li><\/ul>\n\n\n\n<p>Outra op\u00e7\u00e3o para tornar sua mensagem persuasiva \u00e9 usar termos espec\u00edficos em vez de termos gen\u00e9ricos. Em vez de \"Try It Now\" (Experimente agora), por exemplo, voc\u00ea pode usar um texto de CTA como \"Click Here for Your 14-Day Free Trial\" (Clique aqui para obter uma avalia\u00e7\u00e3o gratuita de 14 dias). Isso dar\u00e1 aos visitantes uma no\u00e7\u00e3o mais clara do que eles obter\u00e3o ao seguir a a\u00e7\u00e3o sugerida.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2_Choose_the_Right_Colors\"><\/span>2. Escolha as cores certas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"wp-block-image wp-image-3449 size-full\"><figure class=\"aligncenter\"><img decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/aquaspresso-cta-1.jpg\" alt=\"Bot\u00e3o colorido de chamada para a\u00e7\u00e3o do Aquaspresso\" class=\"wp-image-3449\" srcset=\"https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/aquaspresso-cta-1.jpg 800w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/aquaspresso-cta-1-300x150.jpg 300w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/aquaspresso-cta-1-768x384.jpg 768w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/aquaspresso-cta-1-284x142.jpg 284w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/aquaspresso-cta-1-540x270.jpg 540w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/aquaspresso-cta-1-156x78.jpg 156w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption>O uso do amarelo no CTA da Aquaspresso garante que a mensagem se destaque.<\/figcaption><\/figure><\/div>\n\n\n\n<p>Embora as palavras que voc\u00ea usa sejam importantes, a apresenta\u00e7\u00e3o tamb\u00e9m \u00e9. A apar\u00eancia do seu bot\u00e3o de CTA pode ter um efeito dr\u00e1stico no seu sucesso. \u00c9 por isso que voc\u00ea deve <a href=\"https:\/\/blog.hubspot.com\/blog\/tabid\/6307\/bid\/20566\/The-Button-Color-A-B-Test-Red-Beats-Green.aspx\" target=\"_blank\" rel=\"noopener noreferrer\">escolha as cores certas<\/a>&nbsp;ao projetar uma CTA.<\/p>\n\n\n\n<p>Entretanto, a melhor op\u00e7\u00e3o de cor para um site pode n\u00e3o ser a ideal para outro. Como v\u00e1rias cores t\u00eam conota\u00e7\u00f5es diferentes, voc\u00ea precisar\u00e1 dedicar algum tempo para considerar seus objetivos e a impress\u00e3o geral que deseja dar aos visitantes.<\/p>\n\n\n\n<p>Mais importante ainda, voc\u00ea vai querer:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Escolha <\/strong><strong>uma emo\u00e7\u00e3o<\/strong><strong>. <\/strong>Por exemplo, o vermelho \u00e9 uma op\u00e7\u00e3o s\u00f3lida se voc\u00ea quiser projetar um senso de urg\u00eancia. No entanto, se voc\u00ea preferir promover uma sensa\u00e7\u00e3o de seguran\u00e7a para compradores mais relutantes, o azul \u00e9 sua melhor aposta.<\/li><li><strong>Considere o contraste<\/strong><strong>. <\/strong>Voc\u00ea tamb\u00e9m deve pensar em como as cores da CTA ficar\u00e3o no contexto do seu website. \u00c9 necess\u00e1rio que a CTA se destaque, o que significa que voc\u00ea deve usar cores que contrastem com o restante do design.<\/li><\/ul>\n\n\n\n<p>Lembre-se de que n\u00e3o h\u00e1 regras r\u00edgidas e r\u00e1pidas quando se trata de sele\u00e7\u00e3o de cores. Entretanto, seguindo as diretrizes gerais acima, voc\u00ea ter\u00e1 um bom come\u00e7o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_Display_Your_CTA_in_a_Prominent_Location\"><\/span>3. Exiba sua CTA em um local de destaque<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"wp-block-image wp-image-3450\"><figure class=\"aligncenter\"><img decoding=\"async\" width=\"1725\" height=\"636\" src=\"https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/officevibe-cta-1.jpg\" alt=\"Chamada \u00e0 a\u00e7\u00e3o do OfficeVibe colocada em destaque\" class=\"wp-image-3450\" srcset=\"https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/officevibe-cta-1.jpg 1725w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/officevibe-cta-1-300x111.jpg 300w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/officevibe-cta-1-1024x378.jpg 1024w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/officevibe-cta-1-768x283.jpg 768w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/officevibe-cta-1-1536x566.jpg 1536w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/officevibe-cta-1-385x142.jpg 385w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/officevibe-cta-1-732x270.jpg 732w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/officevibe-cta-1-1216x448.jpg 1216w, https:\/\/easyaffiliate.com\/wp-content\/uploads\/2018\/07\/officevibe-cta-1-156x58.jpg 156w\" sizes=\"(max-width: 1725px) 100vw, 1725px\" \/><figcaption>O Officevibe coloca sua CTA no canto superior direito do site, onde \u00e9 vista pela maioria dos visitantes.<\/figcaption><\/figure><\/div>\n\n\n\n<p>N\u00e3o s\u00f3 a apar\u00eancia da sua CTA desempenha um papel importante no sucesso dela, <em>onde<\/em> ele est\u00e1 posicionado tamb\u00e9m tem um efeito significativo. Isso ocorre porque as pessoas costumam ler sites em um padr\u00e3o em forma de F. Em geral, isso significa que as CTAs ter\u00e3o melhor desempenho quando colocadas na parte superior da p\u00e1gina ou em algum lugar pr\u00f3ximo ao meio.<\/p>\n\n\n\n<p>No entanto, existem <a href=\"https:\/\/www.nngroup.com\/articles\/eyetracking-tasks-efficient-scanning\/\" target=\"_blank\" rel=\"noopener noreferrer\">outros padr\u00f5es de varredura<\/a>&nbsp;seus visitantes podem seguir, portanto, \u00e9 melhor testar e otimizar o posicionamento de cada CTA. Para isso, voc\u00ea pode:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Use um mapa de calor<\/strong><strong>. <\/strong>Esse tipo de ferramenta o ajudar\u00e1 a ver quais posicionamentos funcionam melhor em seu site e destacar\u00e1 onde os visitantes tendem a interagir com suas p\u00e1ginas e postagens com mais frequ\u00eancia.<\/li><li><strong>Use CTAs com modera\u00e7\u00e3o. <\/strong>Se voc\u00ea tiver v\u00e1rias CTAs muito pr\u00f3ximas, poder\u00e1 confundir seu p\u00fablico-alvo. Seja cuidadoso com o local onde coloca as CTAs, sempre considerando a experi\u00eancia do usu\u00e1rio.<\/li><\/ul>\n\n\n\n<p>N\u00e3o tenha medo de testar diferentes posicionamentos, pois essa ser\u00e1 a \u00fanica maneira de saber quais locais s\u00e3o mais bem-sucedidos em seu site.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Conclus\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Ter uma CTA poderosa \u00e9 fundamental para tornar seu site de afiliados lucrativo. Se voc\u00ea puder criar uma CTA que persuada as pessoas a realizarem a a\u00e7\u00e3o que voc\u00ea deseja, estar\u00e1 em uma posi\u00e7\u00e3o s\u00f3lida para aumentar suas convers\u00f5es e sua receita.<\/p>\n\n\n\n<p>Neste artigo, discutimos tr\u00eas maneiras de criar uma CTA eficaz. S\u00e3o elas:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Torne a mensagem envolvente e persuasiva.<\/li><li>Escolha as cores certas.<\/li><li>Exiba sua CTA em um local de destaque.<\/li><\/ol>\n\n\n\n<p>Voc\u00ea tem alguma d\u00favida sobre como potencializar as CTAs de seu website? Fale conosco na se\u00e7\u00e3o de coment\u00e1rios abaixo!<\/p>\n\n\n\n<p>Se voc\u00ea gostou deste post, n\u00e3o deixe de nos seguir em <a href=\"https:\/\/twitter.com\/easyaffapp\"><strong>Twitter<\/strong><\/a>, <a href=\"https:\/\/www.facebook.com\/easyaffiliateplugin\"><strong>Facebook<\/strong><\/a>e <a href=\"https:\/\/www.linkedin.com\/showcase\/easy-affiliate-plugin\/?viewAsMember=true\"><strong>LinkedIn<\/strong><\/a>! E n\u00e3o se esque\u00e7a de se inscrever no <a href=\"https:\/\/easyaffiliate.com\/pt\/go\/box\/\" title=\"Link de afiliado da caixa\" class=\"pretty-link-keyword\"rel=\"nofollow \" target=\"_blank\">caixa<\/a> abaixo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Every affiliate site has an express purpose, a single goal it&#8217;s guiding visitors toward: the end of the sales funnel. Before visitors can reach this goal they\u2019ll need to complete a specific action. The key is getting them to take that final plunge. This is where your call to action (CTA) comes into play. A [&hellip;]<\/p>\n","protected":false},"author":1592,"featured_media":3488,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_strive_editorial_status":"not-started","_strive_copy_of":0,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_strive_checklists":"\"\"","_strive_active_checklist":"","_strive_post_notes":"","footnotes":""},"categories":[312,314],"tags":[283],"class_list":{"0":"post-3447","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-advice","8":"category-tutorials","9":"tag-content-optimization","10":"entry"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/easyaffiliate.com\/pt\/wp-json\/wp\/v2\/posts\/3447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyaffiliate.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/easyaffiliate.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/easyaffiliate.com\/pt\/wp-json\/wp\/v2\/users\/1592"}],"replies":[{"embeddable":true,"href":"https:\/\/easyaffiliate.com\/pt\/wp-json\/wp\/v2\/comments?post=3447"}],"version-history":[{"count":0,"href":"https:\/\/easyaffiliate.com\/pt\/wp-json\/wp\/v2\/posts\/3447\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/easyaffiliate.com\/pt\/wp-json\/wp\/v2\/media\/3488"}],"wp:attachment":[{"href":"https:\/\/easyaffiliate.com\/pt\/wp-json\/wp\/v2\/media?parent=3447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/easyaffiliate.com\/pt\/wp-json\/wp\/v2\/categories?post=3447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/easyaffiliate.com\/pt\/wp-json\/wp\/v2\/tags?post=3447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}